{"id":1356,"date":"2018-03-14T08:29:56","date_gmt":"2018-03-14T08:29:56","guid":{"rendered":"http:\/\/4-pack.com\/it\/?p=1356"},"modified":"2024-02-23T13:16:34","modified_gmt":"2024-02-23T13:16:34","slug":"simboli-etichette-alimentari","status":"publish","type":"post","link":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/","title":{"rendered":"Simboli etichette alimentari"},"content":{"rendered":"<h2>Simboli e pittogrammi per rendere chiare le etichette<\/h2>\n<p>&nbsp;<\/p>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"Simbolo 4PACK spiga barrata\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4Flying_SITE_2017_Images\/simbolo-spiga-barrata.gif\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Marchio Spiga Barrata<\/h3>\n<p>La spiga barrata \u00e8 un simbolo registrato di propriet\u00e0 dell\u2019Associazione Italiana Celiachia (AIC). Il simbolo \u00e8 riportato su tutti quei prodotti per i quali \u00e8 stata accertata l\u2019idoneit\u00e0 al consumo da parte dei celiaci, sia attraverso i controlli eseguiti sul cilco produttivo che sui prodotti stessi. Viene concesso previa la sottoscrizione di un contratto tra AIC e l\u2019Azienda interessata e la successiva verifica da parte di AIC dell\u2019idoneit\u00e0 dei prodotti. ll marchio Spiga Barrata \u00e8 riportato sull&#8217;etichetta di sempre pi\u00f9 numerosi prodotti alimentari e rientra in un ampio progetto che AIC ha attivato per favorire una sempre migliore qualit\u00e0 della vita dei soggetti celiaci e delle loro famiglie.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"simbolo 4PACK halal\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-halal_1.jpg\" alt=\"simbolo 4PACK halal\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Certificazione Halal<\/h3>\n<p>Halal in arabo significa &#8220;lecito&#8221; e la certificazione Halal attesta che i prodotti, nei settori agroalimentare, cosmetico, sanitario, farmaceutico, finanziario e assicurativo, siano conformi alla dottrina islamica. \u00c8 dunque una certificazione di qualit\u00e0, di filiera e di prodotto. La certificazione Halal garantisce che i cibi, oltre a essere conformi alle normative italiane ed europee in tema di igiene e sicurezza, siano preparati secondo le regole della sharia. Tutti gli alimenti sono considerati halal,esclusi i seguenti, che sono haram:<\/p>\n<ul>\n<li>carne di maiale ed i suoi derivati<\/li>\n<li>alcol e sostanze inebrianti<\/li>\n<li>tutti gli alimenti provenire da animali che, se per loro stessa natura sono halal, leciti (agnello, montone, caprini ecc), non siano stati macellati ritualmente in accordo con la shari\u2019a islamica<\/li>\n<li>qualsiasi cosa possa essere ritenuta dannosa per la nostra salute<\/li>\n<\/ul>\n<p>Infine, tutti i prodotti, per essere dichiarati halal, devono essere esenti da ogni contaminazione derivata dall\u2019essere entrato in contatto con sostanze haram durante la loro preparazione, la loro produzione,la loro trasformazione ed il loro confezionamento. Per la carne tuttavia, ci sono requisiti molto pi\u00f9 severi. Alcune carni specifiche sono considerate come Haram (ad es. il maiale ed i suoi derivati); altre sono Halal se i principi della macellazione Halal sono rispettati.<\/p>\n<p>Tali principi possono essere definiti secondo le seguenti modalit\u00e0:<\/p>\n<ul>\n<li>il benessere degli animali gli animali devono essere vivi presso il macello<\/li>\n<li>i macellai musulmani devono pronunciare il nome di Dio prima della macellazione<\/li>\n<li>la macellazione deve essere eseguita nel modo pi\u00f9 umano possibile<\/li>\n<li>il sangue \u00e8 Haram, di conseguenza va eliminato dalla carcassa la carne dovr\u00e0 essere manipolata con la massima cura per evitare la contaminazione incrociata con prodotti Haram<\/li>\n<li>Se uno qualsiasi di questi principi \u00e8 compromesso, la carne sar\u00e0 considerata Haram.<\/li>\n<\/ul>\n<p>In Italia la certificazione viene eseguita dall\u2019Halal Italy Authority ed \u00e8 riconosciuta a livello internazionale. \u00c8 un marchio di garanzia importante per le aziende che vogliono posizionarsi nel mercato islamico e soddisfare le esigenze dei consumatori di fede musulmana.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo vegan\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-vegan_1.jpg\" alt=\"Simbolo 4PACK vegan\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Marchio Vegan<\/h3>\n<p>Sono diversi i simboli relativi all\u2019alimentazione vegana. Tutti indicano che l\u2019alimento \u00e8 adatto proprio a questo tipo di alimentazione, che prevede l\u2019esclusione volontaria dei prodotti di origine animale e loro derivati (carne, pesce, latte, uova, miele).<\/p>\n<p>Il marchio vegan (VeganOk, Vegan Society, Qualit\u00e0 Vegana, ecc) \u00e8 un simbolo ottenuto grazie a un\u2019autocertificazione a pagamento nel rispetto della normativa Europea UNI EN ISO 14021. Questa normativa, denominata semplicemente anche certificazione ambientale di prodotto, garantisce che l\u2019azienda che appone il marchio sia responsabile civilmente e penalmente di quanto dichiarato.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo bicchiere e forchetta\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK\/simbolo-bicchiere-forchetta_1.jpg\" alt=\"4PACK simbolo bicchiere e forchetta\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Simbolo Bicchiere e forchetta<\/h3>\n<p>Questo simbolo viene apposto per indicare quali oggetti sono idonei al contatto con gli alimenti. I prodotti che recano questo simbolo sono conformi al relativo regolamento UE (1935\/2004 CE) e non rilasciano sostanze nocive negli alimenti.<\/p>\n<p>Lo troviamo in genere su palette da cucina, bicchieri in plastica oppure barattoli per la conservazione di vivande. I prodotti che recano questo simbolo sono conformi al relativo regolamento UE e, tra le altre cose, non rilasciano sostanze nocive negli alimenti.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo codice a barre\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-codice-barre_1.jpg\" alt=\"4PACK simbolo codice a barre\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Codice a barre<\/h3>\n<p>I prodotti alimentari commercializzati riportano un codice a barre, ma qual \u00e8 il significato dei numeri che vi compaiono?<\/p>\n<p>I primi due flag identificano l\u2019autorit\u00e0 nazionale di codifica, i successivi 5 flag identificano il codice del produttore e le ulteriori 5 cifre il prodotto fra i vari prodotti dell\u2019azienda. L\u2019ultimo numero serve solamente come verifica, in modo che il computer possa accorgersi di un\u2019eventuale \u201csvista\u201d. Il codice ha lo scopo di facilitare e velocizzare la logistica e l\u2019operazione di incasso.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo qr code\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-qr-code_1.jpg\" alt=\"4PACK simbolo qr code\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>QR code<\/h3>\n<p>I QR Code (acronimo di Quick Response code, &#8220;Codice a risposta rapida&#8221;) sono piccoli simboli bidimensionali, supporti per l&#8217;archiviazione di piccole quantit\u00e0 di dati o informazioni. Inventati come alternativa ai codici a barre, all\u2019inizio sono stati usati per tracciare e identificare rapidamente materiali e prodotti all&#8217;interno di magazzini e aziende.<\/p>\n<p>Con il passare degli anni, le funzioni del QR code sono cambiate profondamente. Pur essendo ancora oggi utilizzati all&#8217;interno dei magazzini e aziende sono sempre di pi\u00f9 le societ\u00e0 che utilizzano i codici QR come mezzo di comunicazione o informativo per ampliare i contenuti delle etichette.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo riciclaggio\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-riciclaggio_1.jpg\" alt=\"4PACK simbolo riciclaggio\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Simboli del riciclaggio<\/h3>\n<p>Il simbolo di riciclaggio \u00e8 il simbolo internazionale che indica il riciclaggio dei rifiuti. \u00c8 composto da tre frecce che formano un nastro di M\u00f6bius. Si trova su imballaggi di carta, cartone e cellulosa. Significa che il prodotto \u00e8 riciclabile ma anche che la confezione \u00e8 composta da materiali riciclati..<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo riciclaggio tre frecce\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-tre-frecce_1.jpg\" alt=\"4PACK simbolo riciclaggio tre frecce\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<p>Invece, il simbolo con le tre frecce strette che si inseguono si trovano negli imballaggi in plastica, con un numero o una sigla riferita al materiale impiegato. I numeri presenti al suo interno, da 1 a 6, indicano il tipo di plastica utilizzata secondo un codice prestabilito. In alcuni casi numero \u00e8 accompagnato anche da sigle. La presenza del numero 7 indica che il materiale non \u00e8 riciclabile.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo uomo che butta nel cestino\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-omino-cestino_1.jpg\" alt=\"4PACK simbolo uomo che butta nel cestino\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<p>Il simbolo dell\u2019uomo che getta la carta nel cestino indica che il prodotto non \u00e8 conforme alle norme che regolano la raccolta differenziata, pertanto il rifiuto va gettato nell\u2019indiferrenziata.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo punto verde\" src=\"https:\/\/bucket-4flying.4flow.cloud\/webimg\/4PACK_IMMAGINI\/THUMB_simbolo-punto-verde_1.jpg.jpg\" alt=\"4PACK simbolo punto verde\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Punto Verde<\/h3>\n<p>Soprattutto nel Nord Europa e in Germania, il marchio chiamato Punto Verde o Der Grune Punk attesta che il produttore aderisce ai consorzi che organizzano il recupero e il riciclaggio degli imballaggi.<\/p>\n<p>Il Punto Verde individua chi si occupa della raccolta e dello smaltimento del rifiuto, mentre non specifica niente riguardo alla riciclabilit\u00e0 del prodotto o alla presenza di materiale riciclabile, funzione che \u00e8 svolta dagli altri simboli. Le aziende che esportano in altri paesi europei dove tali consorzi sono gi\u00e0 funzionanti, lo inseriscono negli imballaggi o sulle etichette dei loro prodotti laddove aderiscono ai consorzi citati.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK marchio FSC\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-fsc_1.jpg\" alt=\"4PACK marchio FSC\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Il marchio FSC<\/h3>\n<p>Il marchio FSC\u00ae identifica i prodotti contenenti legno proveniente da foreste gestite in maniera corretta e responsabile secondo rigorosi standard ambientali, sociali ed economici.<\/p>\n<p>La foresta di origine \u00e8 stata controllata e valutata in maniera indipendente in conformit\u00e0 a questi standard stabiliti ed approvati dal Forest Stewardship Council\u00ae a.c. tramite la partecipazione e il consenso delle parti interessate.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo di stima\" src=\"https:\/\/bucket-4flying.4flow.cloud\/OBJECTS\/4PACK_IMMAGINI\/simbolo-e_1.jpg\" alt=\"4PACK simbolo di stima\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>Simbolo di stima<\/h3>\n<p>l simbolo di stima (e) \u00e8 un marchio CEE e indica la parola Europa. Ogni paese europeo possiede dei meccanismi automatici standard che permettono di monitorare la quantit\u00e0 del prodotto. Se questa stima \u00e8 rispettata i produttori possono apporre la lettera e.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo DOP denominazione origine\" src=\"https:\/\/bucket-4flying.4flow.cloud\/webimg\/4PACK_IMMAGINI\/THUMB_simbolo-dop_1.jpg.jpg\" alt=\"4PACK simbolo DOP denominazione origine\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>DOP<\/h3>\n<p>Per &#8220;denominazione d&#8217;origine&#8221; si intende il nome di un&#8217;area geografica delimitata che designa un prodotto alimentare originario di quel luogo e le cui caratteristiche sono esclusivamente dell&#8217;ambiente geografico (comprensivo dei fattori naturali ed umani).<\/p>\n<p>Tutte le fasi, sia la produzione, che la trasformazione ed elaborazione devono avvenire nell&#8217;area stessa. Il processo produttivo deve essere conforme ad un disciplinare di produzione.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo IGP indicazione geografica protetta\" src=\"https:\/\/bucket-4flying.4flow.cloud\/webimg\/4PACK_IMMAGINI\/THUMB_simbolo-igp_1.jpg.jpg\" alt=\"4PACK simbolo IGP indicazione geografica protetta\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>IGP<\/h3>\n<p>Per &#8220;indicazione geografica protetta&#8221; si intende il nome di un&#8217;area geografica determinata che designa un prodotto alimentare originario di tale zona e di cui una determinata qualit\u00e0, o un&#8217;altra caratteristica possa essere attribuita all&#8217;origine geografica.<\/p>\n<p>Una delle fasi, la produzione, e\/o trasformazione, e\/o elaborazione avvenga nell&#8217;area stessa. Il processo produttivo deve essere conforme ad un Disciplinare di produzione.<\/p>\n<\/div>\n<\/div>\n<div class=\"row padding-30\">\n<div class=\"col-xs-12 col-sm-4\"><img decoding=\"async\" class=\"img-responsive\" title=\"4PACK simbolo STG specialit\u00e0 tradizionali garantite\" src=\"https:\/\/bucket-4flying.4flow.cloud\/webimg\/4PACK_IMMAGINI\/THUMB_simbolo-stg_1.jpg.jpg\" alt=\"4PACK simbolo STG specialit\u00e0 tradizionali garantite\" width=\"200px\" \/><\/div>\n<div class=\"col-xs-12 col-sm-8\">\n<h3>STG<\/h3>\n<p>Per \u201cSpecialit\u00e0 Tradizionali Garantite\u201d, si identificano quei prodotti agroalimentari, non legati nello specifico ad un territorio, ma tali che si caratterizzano per i metodi di produzione tradizionali.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Simboli e pittogrammi per rendere chiare le etichette &nbsp; Marchio Spiga Barrata La spiga barrata \u00e8 un simbolo registrato di propriet\u00e0 dell\u2019Associazione Italiana Celiachia (AIC). Il simbolo \u00e8 riportato su tutti quei prodotti per i quali \u00e8 stata accertata l\u2019idoneit\u00e0 al consumo da parte dei celiaci, sia attraverso i controlli eseguiti sul cilco produttivo che [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorised"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Simboli etichette alimentari<\/title>\n<meta name=\"description\" content=\"Sugli imballi dei prodotti alimentari, ma non solo, troviamo molti simboli. Il loro scopo \u00e8 quello di garantire un\u2019informazione corretta e non ingannevole. Vediamo quali sono i simboli\/pittogrammi pi\u00f9 usati e il loro significato.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simboli etichette alimentari\" \/>\n<meta property=\"og:description\" content=\"Sugli imballi dei prodotti alimentari, ma non solo, troviamo molti simboli. Il loro scopo \u00e8 quello di garantire un\u2019informazione corretta e non ingannevole. Vediamo quali sono i simboli\/pittogrammi pi\u00f9 usati e il loro significato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/\" \/>\n<meta property=\"og:site_name\" content=\"4 Pack Italian\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-14T08:29:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-23T13:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/4-pack.com\/it\/wp-content\/uploads\/sites\/2\/2018\/03\/14_label-symbol-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1377\" \/>\n\t<meta property=\"og:image:height\" content=\"866\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"4packrussell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"4packrussell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/\"},\"author\":{\"name\":\"4packrussell\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/#\\\/schema\\\/person\\\/6c7bf04fa04f5c3c934e47fddb96e74d\"},\"headline\":\"Simboli etichette alimentari\",\"datePublished\":\"2018-03-14T08:29:56+00:00\",\"dateModified\":\"2024-02-23T13:16:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/\"},\"wordCount\":1309,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4-pack.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/14_label-symbol-1.jpg\",\"articleSection\":[\"Uncategorised\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/\",\"url\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/\",\"name\":\"Simboli etichette alimentari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4-pack.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/14_label-symbol-1.jpg\",\"datePublished\":\"2018-03-14T08:29:56+00:00\",\"dateModified\":\"2024-02-23T13:16:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/#\\\/schema\\\/person\\\/6c7bf04fa04f5c3c934e47fddb96e74d\"},\"description\":\"Sugli imballi dei prodotti alimentari, ma non solo, troviamo molti simboli. Il loro scopo \u00e8 quello di garantire un\u2019informazione corretta e non ingannevole. Vediamo quali sono i simboli\\\/pittogrammi pi\u00f9 usati e il loro significato.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/4-pack.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/14_label-symbol-1.jpg\",\"contentUrl\":\"https:\\\/\\\/4-pack.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/03\\\/14_label-symbol-1.jpg\",\"width\":1377,\"height\":866},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/simboli-etichette-alimentari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/4-pack.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simboli etichette alimentari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/4-pack.com\\\/it\\\/\",\"name\":\"4 Pack Italian\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/4-pack.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/4-pack.com\\\/it\\\/#\\\/schema\\\/person\\\/6c7bf04fa04f5c3c934e47fddb96e74d\",\"name\":\"4packrussell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d32aba110c023893ef9e787471e3a0cbbd6bf69d3179e13d5d295610965084e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d32aba110c023893ef9e787471e3a0cbbd6bf69d3179e13d5d295610965084e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d32aba110c023893ef9e787471e3a0cbbd6bf69d3179e13d5d295610965084e?s=96&d=mm&r=g\",\"caption\":\"4packrussell\"},\"url\":\"https:\\\/\\\/4-pack.com\\\/it\\\/knowledge-centre\\\/author\\\/4packrussell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simboli etichette alimentari","description":"Sugli imballi dei prodotti alimentari, ma non solo, troviamo molti simboli. Il loro scopo \u00e8 quello di garantire un\u2019informazione corretta e non ingannevole. Vediamo quali sono i simboli\/pittogrammi pi\u00f9 usati e il loro significato.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/","og_locale":"it_IT","og_type":"article","og_title":"Simboli etichette alimentari","og_description":"Sugli imballi dei prodotti alimentari, ma non solo, troviamo molti simboli. Il loro scopo \u00e8 quello di garantire un\u2019informazione corretta e non ingannevole. Vediamo quali sono i simboli\/pittogrammi pi\u00f9 usati e il loro significato.","og_url":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/","og_site_name":"4 Pack Italian","article_published_time":"2018-03-14T08:29:56+00:00","article_modified_time":"2024-02-23T13:16:34+00:00","og_image":[{"width":1377,"height":866,"url":"https:\/\/4-pack.com\/it\/wp-content\/uploads\/sites\/2\/2018\/03\/14_label-symbol-1.jpg","type":"image\/jpeg"}],"author":"4packrussell","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"4packrussell","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#article","isPartOf":{"@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/"},"author":{"name":"4packrussell","@id":"https:\/\/4-pack.com\/it\/#\/schema\/person\/6c7bf04fa04f5c3c934e47fddb96e74d"},"headline":"Simboli etichette alimentari","datePublished":"2018-03-14T08:29:56+00:00","dateModified":"2024-02-23T13:16:34+00:00","mainEntityOfPage":{"@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/"},"wordCount":1309,"commentCount":0,"image":{"@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#primaryimage"},"thumbnailUrl":"https:\/\/4-pack.com\/it\/wp-content\/uploads\/sites\/2\/2018\/03\/14_label-symbol-1.jpg","articleSection":["Uncategorised"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/","url":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/","name":"Simboli etichette alimentari","isPartOf":{"@id":"https:\/\/4-pack.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#primaryimage"},"image":{"@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#primaryimage"},"thumbnailUrl":"https:\/\/4-pack.com\/it\/wp-content\/uploads\/sites\/2\/2018\/03\/14_label-symbol-1.jpg","datePublished":"2018-03-14T08:29:56+00:00","dateModified":"2024-02-23T13:16:34+00:00","author":{"@id":"https:\/\/4-pack.com\/it\/#\/schema\/person\/6c7bf04fa04f5c3c934e47fddb96e74d"},"description":"Sugli imballi dei prodotti alimentari, ma non solo, troviamo molti simboli. Il loro scopo \u00e8 quello di garantire un\u2019informazione corretta e non ingannevole. Vediamo quali sono i simboli\/pittogrammi pi\u00f9 usati e il loro significato.","breadcrumb":{"@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#primaryimage","url":"https:\/\/4-pack.com\/it\/wp-content\/uploads\/sites\/2\/2018\/03\/14_label-symbol-1.jpg","contentUrl":"https:\/\/4-pack.com\/it\/wp-content\/uploads\/sites\/2\/2018\/03\/14_label-symbol-1.jpg","width":1377,"height":866},{"@type":"BreadcrumbList","@id":"https:\/\/4-pack.com\/it\/knowledge-centre\/simboli-etichette-alimentari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/4-pack.com\/it\/"},{"@type":"ListItem","position":2,"name":"Simboli etichette alimentari"}]},{"@type":"WebSite","@id":"https:\/\/4-pack.com\/it\/#website","url":"https:\/\/4-pack.com\/it\/","name":"4 Pack Italian","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/4-pack.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/4-pack.com\/it\/#\/schema\/person\/6c7bf04fa04f5c3c934e47fddb96e74d","name":"4packrussell","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7d32aba110c023893ef9e787471e3a0cbbd6bf69d3179e13d5d295610965084e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d32aba110c023893ef9e787471e3a0cbbd6bf69d3179e13d5d295610965084e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d32aba110c023893ef9e787471e3a0cbbd6bf69d3179e13d5d295610965084e?s=96&d=mm&r=g","caption":"4packrussell"},"url":"https:\/\/4-pack.com\/it\/knowledge-centre\/author\/4packrussell\/"}]}},"_links":{"self":[{"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/posts\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":1,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/posts\/1356\/revisions"}],"predecessor-version":[{"id":1357,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/posts\/1356\/revisions\/1357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/media\/1984"}],"wp:attachment":[{"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/categories?post=1356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/4-pack.com\/it\/wp-json\/wp\/v2\/tags?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}